{"id":181,"count":17,"description":"","link":"https:\/\/imperial-line.com\/fr\/bois\/","name":"Bois","slug":"bois","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bois Archivi - Imperial Line<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/imperial-line.com\/fr\/bois\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bois Archivi - Imperial Line\" \/>\n<meta property=\"og:url\" content=\"https:\/\/imperial-line.com\/fr\/bois\/\" \/>\n<meta property=\"og:site_name\" content=\"Imperial Line\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/imperial-line.com\/fr\/bois\/\",\"url\":\"https:\/\/imperial-line.com\/fr\/bois\/\",\"name\":\"Bois Archivi - Imperial Line\",\"isPartOf\":{\"@id\":\"https:\/\/imperial-line.com\/fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/imperial-line.com\/fr\/bois\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/imperial-line.com\/fr\/bois\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/imperial-line.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bois\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/imperial-line.com\/fr\/#website\",\"url\":\"https:\/\/imperial-line.com\/fr\/\",\"name\":\"Imperial Line\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/imperial-line.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/imperial-line.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/imperial-line.com\/fr\/#organization\",\"name\":\"Imperial Line\",\"url\":\"https:\/\/imperial-line.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/imperial-line.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/imperial-line.com\/wp-content\/uploads\/2024\/05\/logo-black.png\",\"contentUrl\":\"https:\/\/imperial-line.com\/wp-content\/uploads\/2024\/05\/logo-black.png\",\"width\":2000,\"height\":160,\"caption\":\"Imperial Line\"},\"image\":{\"@id\":\"https:\/\/imperial-line.com\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bois Archivi - Imperial Line","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/imperial-line.com\/fr\/bois\/","og_locale":"fr_FR","og_type":"article","og_title":"Bois Archivi - Imperial Line","og_url":"https:\/\/imperial-line.com\/fr\/bois\/","og_site_name":"Imperial Line","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/imperial-line.com\/fr\/bois\/","url":"https:\/\/imperial-line.com\/fr\/bois\/","name":"Bois Archivi - Imperial Line","isPartOf":{"@id":"https:\/\/imperial-line.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/imperial-line.com\/fr\/bois\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/imperial-line.com\/fr\/bois\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/imperial-line.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Bois"}]},{"@type":"WebSite","@id":"https:\/\/imperial-line.com\/fr\/#website","url":"https:\/\/imperial-line.com\/fr\/","name":"Imperial Line","description":"","publisher":{"@id":"https:\/\/imperial-line.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/imperial-line.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/imperial-line.com\/fr\/#organization","name":"Imperial Line","url":"https:\/\/imperial-line.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/imperial-line.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/imperial-line.com\/wp-content\/uploads\/2024\/05\/logo-black.png","contentUrl":"https:\/\/imperial-line.com\/wp-content\/uploads\/2024\/05\/logo-black.png","width":2000,"height":160,"caption":"Imperial Line"},"image":{"@id":"https:\/\/imperial-line.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/imperial-line.com\/fr\/wp-json\/wp\/v2\/categories\/181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imperial-line.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/imperial-line.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/imperial-line.com\/fr\/wp-json\/wp\/v2\/posts?categories=181"},{"href":"https:\/\/imperial-line.com\/fr\/wp-json\/wp\/v2\/download?categories=181"},{"href":"https:\/\/imperial-line.com\/fr\/wp-json\/wp\/v2\/finiture?categories=181"},{"href":"https:\/\/imperial-line.com\/fr\/wp-json\/wp\/v2\/news?categories=181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}